{"id":8268,"date":"2024-05-09T09:45:50","date_gmt":"2024-05-09T09:45:50","guid":{"rendered":"https:\/\/topautoparts.al\/produkte\/"},"modified":"2025-05-02T11:08:49","modified_gmt":"2025-05-02T11:08:49","slug":"products","status":"publish","type":"page","link":"https:\/\/topautoparts.al\/en\/products\/","title":{"rendered":"PRODUCTS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8268\" class=\"elementor elementor-8268 elementor-2022\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c119889 e-flex e-con-boxed e-con e-parent\" data-id=\"c119889\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9cfeddb e-con-full e-flex e-con e-child\" data-id=\"9cfeddb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70f4272 elementor-widget elementor-widget-global elementor-global-7592 elementor-widget-image-carousel\" data-id=\"70f4272\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:700,&quot;speed&quot;:1500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/Bosch-logo-qwnzqvpvhzrsfkns1xusqfsssq3txefdxz2kidq1og.webp\" alt=\"Bosch-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/mann-filter-logo-1-qwnzqus1b5qi3yp57fg65y1c7c8gppbnluf313rfuo.webp\" alt=\"mann-filter-logo (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/tecneco-logo-r0a88gu1q0ik5w6frxspfhfbe5fmmki852a0yzngu8.png\" alt=\"tecneco logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/FILTRON_logo_B_PNG-1-r22uw0zboj1dk4qtryw6rjtztj84xt5h0e4dq2in7k.webp\" alt=\"FILTRON_logo_B_PNG-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/black-logo-filtorq-1-r22uwe52c7je2o7pn4kyqgig4xf9xklpq796fxz4sg.webp\" alt=\"black-logo-filtorq-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/meyle-logo-r0acamqkgklpizv8a4a85llot50dk6rm8ia5hyxla8.png\" alt=\"meyle logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/ATE-logo-1-qwnzqswcxhnxgqrviemx0yif0khqab46xl442ju874.webp\" alt=\"ATE-logo (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/Zimmermann-logo-qwnzqtu74bp7scqicx1jlg9vlyd3i07x9prljtsu0w.webp\" alt=\"Zimmermann-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/png-clipart-car-trw-automotive-trw-inc-automotiv-1e-industry-zf-friedrichshafen-mitsubishi-driving-text-removebg-preview-r22uwkpxo1sebxy5kpfcpwuoamiufgbu33tksvpdkw.webp\" alt=\"png-clipart-car-trw-automotive-trw-inc-automotiv-1e-industry-zf-friedrichshafen-mitsubishi-driving-text-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/ZF-logo-1-qwnxbtvykclt7n3udb8mtem0a3632iuan41qhuslxc.webp\" alt=\"ZF-logo (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/schafller-removebg-preview-r22tqax8b9x679cnexmd32vejsvl9hielvmgtwdreo.png\" alt=\"schafller-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/topran-removebg-preview-r22tqeol2m2bhp76sz8vd1x8xcd249xbye8er086ps.png\" alt=\"topran-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/logo-pierburg-1-r22uvtgm5ur2z91qzvn67lqb2g9788bmbcwhvutslc.webp\" alt=\"logo-pierburg-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/febi-logo-4C-1705-1-r22uw2v0273y7co3gzpfwjcx0ayvd7cxonfcomfuv4.webp\" alt=\"febi-logo-4C-1705-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/delphi-autoparts-logo-png_seeklogo-526619-1-r22uw6mctj93hsimv1by6ierdugc7zrv161alqaa68.webp\" alt=\"delphi-autoparts-logo-png_seeklogo-526619-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/Magneti_Marelli_logo-1-r22uwv25r86jvnj4wbw8zc8qtv3vs4gvsizx2xa1og.webp\" alt=\"Magneti_Marelli_logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/SKF-Logo-1-r22uwg0qpvlypw4zc5e7vg1dbp60cyt6egk5ehwcg0.webp\" alt=\"SKF-Logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/BorgWarner_Beru_Systems_logo-1-r22uwbbjrpfj3ubt3ld30z82crt6ahaiptaq043bb4.webp\" alt=\"BorgWarner_Beru_Systems_logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/monroe-logo-1-r22uwu4bke59k1ki1thmeuha8h8ikfd5gecflnbfuo.webp\" alt=\"monroe-logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/png-transparent-ferodo-hd-logo-removebg-preview-1-r22ux5eduekpfd447yd58rmtd3ox4slxhy69cyups0.webp\" alt=\"png-transparent-ferodo-hd-logo-removebg-preview-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/NGK-Logo-1-r22uwraszw1el7olia9qpd6wgbmexc1yg0dz5tfmdc.webp\" alt=\"NGK-Logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/ky3350k906-kyb-logo-kyb-kayaba-vector-logo-kyb-kayaba-logo-vector-free-download-removebg-preview-1-r22v1ulc0l0bh6acrzhzpkxsagizmb9m57lnqrvuo0.webp\" alt=\"ky3350k906-kyb-logo-kyb-kayaba-vector-logo-kyb-kayaba-logo-vector-free-download-removebg-preview-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/gates-logo-png-transparent-1-scaled-r22uvwa4qcuxy2xnjev1x30oulvavbmtbquybopm2o.webp\" alt=\"gates-logo-png-transparent-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/Continental-logo-qwnzqvpvhzrsfkns1xusqfsssq3txefdxz2kidq1og.webp\" alt=\"Continental-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/NRF-logo-qwnzqvpvhzrsfkns1xusqfsssq3txefdxz2kidq1og.webp\" alt=\"NRF-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/nissens-1-r22uwpf4m7ytxzrbt9ghkdnz9jvohxuhrr3079ieps.webp\" alt=\"nissens-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/png-transparent-valeo-hd-logo-removebg-preview-1-r22uwiu9adptoq0vvom3kxbr3us4024deuilubs5xc.webp\" alt=\"png-transparent-valeo-hd-logo-removebg-preview-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/thermotec-r2zig0byb3wih0lyt0ijw9156xf6egjosus8m69beo.webp\" alt=\"thermotec\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/victor-r22tqeol2m2bhp76sz8vd1x8xcd249xbye8er086ps.png\" alt=\"victor\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/el3527e1c4-elring-logo-elring-logo-png-transparent-amp-svg-vector-freebie-supply-removebg-preview-r22u31mgyfd3kyud0fwavv4cfu2pls3f0xzf0xhn28.png\" alt=\"el3527e1c4-elring-logo-elring-logo-png-transparent-amp-svg-vector-freebie-supply-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/adinol-logo-r0a88fw7j6h9ua7sxfe2uznusrk9evehsxmjhpov0g.png\" alt=\"adinol logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/petrolOfisi-logo-qwnzqtu74bp7scqicx1jlg9vlyd3i07x9prljtsu0w.webp\" alt=\"petrolOfisi-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/logo-castrol-r0ac7lpafsgg489lyt5i4d47wfxsraqr5ilttvf9c0.png\" alt=\"logo castrol\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/selenia-logo-r0acqdj8xo5lzuzxcfa9f4kn0hepho9refnxvtl728.png\" alt=\"selenia logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/mobil-logo-r0acoe3ii9fthhvoxkem5mllv76t8oe5sm31esj474.png\" alt=\"mobil logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/wolver-xTnDZwCcIQr9JyYXMyLP3m3gAkBKw1il08Bv8S1O-r22tta2tydzuyt1017xtzbty9q7fmzbt0lztjfyvpc.webp\" alt=\"wolver-xTnDZwCcIQr9JyYXMyLP3m3gAkBKw1il08Bv8S1O\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/CAT-logo-1-r22uw7k70dadteh9pjqkr067z8bpfovldaos308w00.webp\" alt=\"CAT-logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/Osram_Logo-1-r22uwmlm1puyz5vf9q8luwdlhe9kuujard4jrfml8g.webp\" alt=\"Osram_Logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"39 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/elementor\/thumbs\/Wunder-Baum-logo-r2zig5159a2y32f51kjoqpug5us0gy2chi1o0k2cjk.webp\" alt=\"Wunder Baum logo\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5726b2 e-con-full qodef-elementor-content-grid e-flex e-con e-parent\" data-id=\"b5726b2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2761af0 e-con-full e-flex e-con e-child\" data-id=\"2761af0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9868221 elementor-widget__width-initial elementor-widget elementor-widget-freightexpress_core_section_title\" data-id=\"9868221\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left  \">\n    \t\t<h2 class=\"qodef-m-title\" >\n\t\t\tProducts\t<\/h2>\n\t    <p class=\"qodef-m-description\" > Learn more about our products.<\/p>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6a445f e-con-full qodef-elementor-content-grid e-flex e-con e-parent\" data-id=\"c6a445f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9ff79a7 e-con-full e-flex e-con e-child\" data-id=\"9ff79a7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-552d732 equal-height-prod elementor-widget elementor-widget-freightexpress_core_icon_with_text\" data-id=\"552d732\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m product-title qodef-icon-with-text qodef-layout--top qodef--custom-icon   qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/lubrificating-oils\/\" target=\"_self\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"665\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/Vajra-lubrifikant-Addinol.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/Vajra-lubrifikant-Addinol.webp 1000w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/Vajra-lubrifikant-Addinol-300x200.webp 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/Vajra-lubrifikant-Addinol-768x511.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h4 class=\"qodef-m-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/lubrificating-oils\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">Lubricating Oils<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9fca4db e-con-full e-flex e-con e-child\" data-id=\"9fca4db\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-332a0ed equal-height-prod elementor-widget elementor-widget-freightexpress_core_icon_with_text\" data-id=\"332a0ed\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m product-title qodef-icon-with-text qodef-layout--top qodef--custom-icon   qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/spare-parts\/\" target=\"_self\">\n\t\t\t<img decoding=\"async\" width=\"1200\" height=\"784\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/ate-pads-and-rotors.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/ate-pads-and-rotors.jpg 1200w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/ate-pads-and-rotors-300x196.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/ate-pads-and-rotors-1024x669.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/ate-pads-and-rotors-768x502.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h4 class=\"qodef-m-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/spare-parts\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">Spare Parts for Vehicles<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd7ae40 e-con-full e-flex e-con e-child\" data-id=\"bd7ae40\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21a972f equal-height-prod elementor-widget elementor-widget-freightexpress_core_icon_with_text\" data-id=\"21a972f\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m product-title qodef-icon-with-text qodef-layout--top qodef--custom-icon   qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/parts-for-trucks\/\" target=\"_self\">\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"460\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/febi-NKW-klima-und-heizungsanlage.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/febi-NKW-klima-und-heizungsanlage.jpg 600w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/febi-NKW-klima-und-heizungsanlage-300x230.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h4 class=\"qodef-m-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/parts-for-trucks\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">Spare Parts for Trucks, Buses, and Excavators<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93efa28 e-con-full qodef-elementor-content-grid e-flex e-con e-parent\" data-id=\"93efa28\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-89c2de1 e-con-full e-flex e-con e-child\" data-id=\"89c2de1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f6f00a equal-height-prod elementor-widget elementor-widget-freightexpress_core_icon_with_text\" data-id=\"7f6f00a\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m product-title qodef-icon-with-text qodef-layout--top qodef--custom-icon   qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/sonax.al\/all-products\/\" target=\"_blank\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"972\" height=\"700\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/sonax.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/sonax.webp 972w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/sonax-300x216.webp 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/sonax-768x553.webp 768w\" sizes=\"(max-width: 972px) 100vw, 972px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h4 class=\"qodef-m-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/sonax.al\/all-products\/\" target=\"_blank\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">Vehicle Maintenance Products<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edef2f6 e-con-full e-flex e-con e-child\" data-id=\"edef2f6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0639e23 equal-height-prod elementor-widget elementor-widget-freightexpress_core_icon_with_text\" data-id=\"0639e23\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m product-title qodef-icon-with-text qodef-layout--top qodef--custom-icon   qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/batteries\/\" target=\"_self\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2126\" height=\"1535\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/BOSCH-battery.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/BOSCH-battery.jpg 2126w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/BOSCH-battery-300x217.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/BOSCH-battery-1024x739.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/BOSCH-battery-768x555.jpg 768w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/BOSCH-battery-1536x1109.jpg 1536w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/BOSCH-battery-2048x1479.jpg 2048w\" sizes=\"(max-width: 2126px) 100vw, 2126px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h4 class=\"qodef-m-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/batteries\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">Batteries<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e68474 e-con-full e-flex e-con e-child\" data-id=\"2e68474\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a496677 equal-height-prod elementor-widget elementor-widget-freightexpress_core_icon_with_text\" data-id=\"a496677\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m product-title qodef-icon-with-text qodef-layout--top qodef--custom-icon   qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/tires\/\" target=\"_self\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1216\" height=\"862\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/goma.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/goma.jpeg 1216w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/goma-300x213.jpeg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/goma-1024x726.jpeg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/goma-768x544.jpeg 768w\" sizes=\"(max-width: 1216px) 100vw, 1216px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h4 class=\"qodef-m-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/topautoparts.al\/en\/tires\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">Tires<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0781380 e-flex e-con-boxed e-con e-parent\" data-id=\"0781380\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53c1cb7 elementor-widget elementor-widget-html\" data-id=\"53c1cb7\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<marquee>\n    <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Spare Parts <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\"> \n    Lubricating Oils <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Batteries <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Tires <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Service <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Spare Parts <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\"> \n    Lubricating Oils <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Batteries <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Tires <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Service <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Spare Parts <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\"> \n    Lubricating Oils <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Batteries <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Tires <img decoding=\"async\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2024\/12\/header-arrow-marquee.png\">\n    Service \n<\/marquee>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f45f5d e-con-full qodef-elementor-content-grid e-flex e-con e-parent\" data-id=\"5f45f5d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7c4fd98 e-con-full e-flex e-con e-child\" data-id=\"7c4fd98\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38c8d63 elementor-widget__width-initial elementor-widget elementor-widget-freightexpress_core_section_title\" data-id=\"38c8d63\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left  \">\n    \t\t<h2 class=\"qodef-m-title\" >\n\t\t\tGallery\t<\/h2>\n\t    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2bc3e9f e-flex e-con-boxed e-con e-parent\" data-id=\"2bc3e9f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a19a3ea elementor-widget elementor-widget-qi_addons_for_elementor_image_slider\" data-id=\"a19a3ea\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-slider qodef-qi-fslightbox-popup qodef-popup-gallery qodef-col-num--3 qodef-qi-grid qodef-qi-swiper-container qodef-pagination--inside\" data-options=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;slidesPerView&quot;:&quot;3&quot;,&quot;spaceBetween&quot;:20,&quot;spaceBetweenTablet&quot;:10,&quot;spaceBetweenMobile&quot;:&quot;&quot;,&quot;effect&quot;:&quot;&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;centeredSlides&quot;:true,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;&quot;,&quot;outsideNavigation&quot;:&quot;no&quot;,&quot;outsidePagination&quot;:&quot;no&quot;,&quot;unique&quot;:122,&quot;partialValue&quot;:0,&quot;disablePartialValue&quot;:&quot;&quot;,&quot;parallax&quot;:&quot;no&quot;}\">\n\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8718.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"986\" height=\"944\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8718.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8718.jpg 986w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8718-300x287.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8718-768x735.jpg 768w\" sizes=\"(max-width: 986px) 100vw, 986px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8723.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1141\" height=\"761\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8723.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8723.jpg 1141w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8723-300x200.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8723-1024x683.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8723-768x512.jpg 768w\" sizes=\"(max-width: 1141px) 100vw, 1141px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8724.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2060\" height=\"1374\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8724.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8724.jpg 2060w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8724-300x200.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8724-1024x683.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8724-768x512.jpg 768w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8724-1536x1024.jpg 1536w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8724-2048x1366.jpg 2048w\" sizes=\"(max-width: 2060px) 100vw, 2060px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8838.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1839\" height=\"1227\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8838.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8838.jpg 1839w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8838-300x200.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8838-1024x683.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8838-768x512.jpg 768w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8838-1536x1025.jpg 1536w\" sizes=\"(max-width: 1839px) 100vw, 1839px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8720.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"879\" height=\"1319\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8720.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8720.jpg 879w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8720-200x300.jpg 200w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8720-682x1024.jpg 682w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8720-768x1152.jpg 768w\" sizes=\"(max-width: 879px) 100vw, 879px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8714.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1289\" height=\"1933\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8714.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8714.jpg 1289w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8714-200x300.jpg 200w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8714-683x1024.jpg 683w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8714-768x1152.jpg 768w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8714-1024x1536.jpg 1024w\" sizes=\"(max-width: 1289px) 100vw, 1289px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8715.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1958\" height=\"1306\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8715.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8715.jpg 1958w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8715-300x200.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8715-1024x683.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8715-768x512.jpg 768w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8715-1536x1025.jpg 1536w\" sizes=\"(max-width: 1958px) 100vw, 1958px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8716.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1407\" height=\"2109\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8716.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8716.jpg 1407w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8716-200x300.jpg 200w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8716-683x1024.jpg 683w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8716-768x1151.jpg 768w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8716-1025x1536.jpg 1025w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8716-1366x2048.jpg 1366w\" sizes=\"(max-width: 1407px) 100vw, 1407px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8738.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1128\" height=\"752\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8738.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8738.jpg 1128w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8738-300x200.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8738-1024x683.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8738-768x512.jpg 768w\" sizes=\"(max-width: 1128px) 100vw, 1128px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8833.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1150\" height=\"768\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8833.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8833.jpg 1150w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8833-300x200.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8833-1024x684.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8833-768x513.jpg 768w\" sizes=\"(max-width: 1150px) 100vw, 1150px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8816.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1237\" height=\"826\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8816.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8816.jpg 1237w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8816-300x200.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8816-1024x684.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8816-768x513.jpg 768w\" sizes=\"(max-width: 1237px) 100vw, 1237px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8815.jpg\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1198\" height=\"799\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8815.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8815.jpg 1198w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8815-300x200.jpg 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8815-1024x683.jpg 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8815-768x512.jpg 768w\" sizes=\"(max-width: 1198px) 100vw, 1198px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8795.webp\" data-type=\"image\" data-fslightbox=\"gallery-122\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8795.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8795.webp 2000w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8795-300x200.webp 300w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8795-1024x683.webp 1024w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8795-768x512.webp 768w, https:\/\/topautoparts.al\/wp-content\/uploads\/2025\/01\/205A8795-1536x1025.webp 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\t<\/div>\n\t\t<div class=\"swiper-pagination\"><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21693eb e-con-full e-flex e-con e-parent\" data-id=\"21693eb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-56ebe62 e-con-full e-flex e-con e-child\" data-id=\"56ebe62\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb2eef3 elementor-widget elementor-widget-freightexpress_core_custom_font\" data-id=\"cb2eef3\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_custom_font.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-custom-font-holder\">\n<h3 class=\"qodef-shortcode qodef-m  qodef-custom-font qodef-custom-font-107 qodef-layout--simple    qodef-decoration--arrow qodef--has-appear qodef--predefined-appear qodef--no-decoration\" style=\"color: #FFFFFF;font-size: 50px;line-height: 60px;letter-spacing: 2px\">\n\t    <span class=\"qodef-e-decoration\" style=\"margin: 0 0 5px 0\"><svg class=\"qodef-svg--custom-font-arrow\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"128\" height=\"99\" viewBox=\"0 0 128 99\"><path d=\"m.518-.052 53.988 47.68L-.557 98.564l87.712-.046 40.746-47.516L83.098-.094Z\" fill=\"#f94834\"\/><\/svg><\/span>\t\t\t<span class=\"qodef--word\"><span class=\"qode--char\" style=\"--qode-i:0\">T<\/span><span class=\"qode--char\" style=\"--qode-i:1\">R<\/span><span class=\"qode--char\" style=\"--qode-i:2\">A<\/span><span class=\"qode--char\" style=\"--qode-i:3\">N<\/span><span class=\"qode--char\" style=\"--qode-i:4\">S<\/span><span class=\"qode--char\" style=\"--qode-i:5\">F<\/span><span class=\"qode--char\" style=\"--qode-i:6\">O<\/span><span class=\"qode--char\" style=\"--qode-i:7\">R<\/span><span class=\"qode--char\" style=\"--qode-i:8\">M<\/span><\/span> <span class=\"qodef--word\"><span class=\"qode--char\" style=\"--qode-i:9\">Y<\/span><span class=\"qode--char\" style=\"--qode-i:10\">O<\/span><span class=\"qode--char\" style=\"--qode-i:11\">U<\/span><span class=\"qode--char\" style=\"--qode-i:12\">R<\/span><\/span> <span class=\"qodef--word\"><span class=\"qode--char\" style=\"--qode-i:13\">R<\/span><span class=\"qode--char\" style=\"--qode-i:14\">I<\/span><span class=\"qode--char\" style=\"--qode-i:15\">D<\/span><span class=\"qode--char\" style=\"--qode-i:16\">E<\/span><\/span>\t\t\t\t<\/h3>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb52ee5 e-con-full e-flex e-con e-child\" data-id=\"bb52ee5\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6b78983 e-con-full blur-background  e-flex e-con e-child\" data-id=\"6b78983\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-871f56a elementor-widget__width-initial elementor-widget elementor-widget-freightexpress_core_section_title\" data-id=\"871f56a\" data-element_type=\"widget\" data-widget_type=\"freightexpress_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left  \">\n    \t\t<h2 class=\"qodef-m-title\" style=\"color: #FFFFFF\">\n\t\t\tContact\t<\/h2>\n\t    <p class=\"qodef-m-description\" style=\"color: #FFFFFF\"> Contact us at our phone number or fill out the form to schedule an appointment at our service center:<\/p>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a1ed94 elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_contact_form_7\" data-id=\"4a1ed94\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-contact-form-7 qodef-button--full-width\">\n\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8232-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"8232\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/8268#wpcf7-f8232-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"8232\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8232-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name Surname\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"email@example.com\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" autocomplete=\"phone\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone Number\" value=\"\" type=\"tel\" name=\"tel-1\" \/><\/span>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" value=\"\" type=\"text\" name=\"your-message\" \/><\/span>\n\n<button class=\"wpcf7-form-control wpcf7-submit qodef-button qodef-size--normal qodef-layout--filled qodef-m\" type=\"submit\"><span class=\"qodef-m-text\" data-title= \"Send\">Send<\/span><span class=\"qodef-btn-arrow\"><svg class=\"qodef-svg--button-arrow-standard\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18.476\" height=\"18.044\" viewBox=\"0 0 18.476 18.044\"><g transform=\"translate(9.007 0.992) rotate(45)\"><path d=\"M0,11.312,11.377,0\" transform=\"translate(0 0.011)\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><\/path><path d=\"M8.466,8.661V0H0\" transform=\"translate(2.925 0)\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><\/path><\/g><\/svg><\/span><\/button><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Products Learn more about our products. Lubricating Oils Spare Parts for Vehicles Spare Parts for Trucks, Buses, and Excavators Vehicle Maintenance Products Batteries Tires Spare Parts Lubricating Oils Batteries Tires Service Spare Parts Lubricating Oils Batteries Tires Service Spare Parts Lubricating Oils Batteries Tires Service Gallery TRANSFORM YOUR RIDE Contact Contact us at our phone [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-8268","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/topautoparts.al\/en\/wp-json\/wp\/v2\/pages\/8268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topautoparts.al\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/topautoparts.al\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/topautoparts.al\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/topautoparts.al\/en\/wp-json\/wp\/v2\/comments?post=8268"}],"version-history":[{"count":20,"href":"https:\/\/topautoparts.al\/en\/wp-json\/wp\/v2\/pages\/8268\/revisions"}],"predecessor-version":[{"id":8404,"href":"https:\/\/topautoparts.al\/en\/wp-json\/wp\/v2\/pages\/8268\/revisions\/8404"}],"wp:attachment":[{"href":"https:\/\/topautoparts.al\/en\/wp-json\/wp\/v2\/media?parent=8268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}